{"id":1393,"count":1,"description":"","link":"https:\/\/www.digime.fi\/en\/tag\/artificial-intelligence-for-libraries-en\/","name":"Artificial Intelligence for Libraries","slug":"artificial-intelligence-for-libraries-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Artificial Intelligence for Libraries arkistot - Digime<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.digime.fi\/en\/tag\/artificial-intelligence-for-libraries-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Artificial Intelligence for Libraries arkistot - Digime\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.digime.fi\/en\/tag\/artificial-intelligence-for-libraries-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Digime\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.digime.fi\/wp-content\/uploads\/2023\/06\/logo_digime1200.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.digime.fi\\\/en\\\/tag\\\/artificial-intelligence-for-libraries-en\\\/\",\"url\":\"https:\\\/\\\/www.digime.fi\\\/en\\\/tag\\\/artificial-intelligence-for-libraries-en\\\/\",\"name\":\"Artificial Intelligence for Libraries arkistot - Digime\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.digime.fi\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.digime.fi\\\/en\\\/tag\\\/artificial-intelligence-for-libraries-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.digime.fi\\\/en\\\/tag\\\/artificial-intelligence-for-libraries-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\\\/\\\/www.digime.fi\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Artificial Intelligence for Libraries\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.digime.fi\\\/#website\",\"url\":\"https:\\\/\\\/www.digime.fi\\\/\",\"name\":\"Digime\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.digime.fi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.digime.fi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.digime.fi\\\/#organization\",\"name\":\"Digime\",\"url\":\"https:\\\/\\\/www.digime.fi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.digime.fi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.digime.fi\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/logo_vih_musta.png\",\"contentUrl\":\"https:\\\/\\\/www.digime.fi\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/logo_vih_musta.png\",\"width\":240,\"height\":100,\"caption\":\"Digime\"},\"image\":{\"@id\":\"https:\\\/\\\/www.digime.fi\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Artificial Intelligence for Libraries arkistot - Digime","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.digime.fi\/en\/tag\/artificial-intelligence-for-libraries-en\/","og_locale":"en_US","og_type":"article","og_title":"Artificial Intelligence for Libraries arkistot - Digime","og_url":"https:\/\/www.digime.fi\/en\/tag\/artificial-intelligence-for-libraries-en\/","og_site_name":"Digime","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.digime.fi\/wp-content\/uploads\/2023\/06\/logo_digime1200.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.digime.fi\/en\/tag\/artificial-intelligence-for-libraries-en\/","url":"https:\/\/www.digime.fi\/en\/tag\/artificial-intelligence-for-libraries-en\/","name":"Artificial Intelligence for Libraries arkistot - Digime","isPartOf":{"@id":"https:\/\/www.digime.fi\/#website"},"breadcrumb":{"@id":"https:\/\/www.digime.fi\/en\/tag\/artificial-intelligence-for-libraries-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.digime.fi\/en\/tag\/artificial-intelligence-for-libraries-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/www.digime.fi\/en\/"},{"@type":"ListItem","position":2,"name":"Artificial Intelligence for Libraries"}]},{"@type":"WebSite","@id":"https:\/\/www.digime.fi\/#website","url":"https:\/\/www.digime.fi\/","name":"Digime","description":"","publisher":{"@id":"https:\/\/www.digime.fi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.digime.fi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.digime.fi\/#organization","name":"Digime","url":"https:\/\/www.digime.fi\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.digime.fi\/#\/schema\/logo\/image\/","url":"https:\/\/www.digime.fi\/wp-content\/uploads\/2018\/05\/logo_vih_musta.png","contentUrl":"https:\/\/www.digime.fi\/wp-content\/uploads\/2018\/05\/logo_vih_musta.png","width":240,"height":100,"caption":"Digime"},"image":{"@id":"https:\/\/www.digime.fi\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.digime.fi\/en\/wp-json\/wp\/v2\/tags\/1393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.digime.fi\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.digime.fi\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.digime.fi\/en\/wp-json\/wp\/v2\/posts?tags=1393"},{"href":"https:\/\/www.digime.fi\/en\/wp-json\/wp\/v2\/tribe_events?tags=1393"},{"href":"https:\/\/www.digime.fi\/en\/wp-json\/wp\/v2\/tec_calendar_embed?tags=1393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}